{"id":3,"count":1,"description":"","link":"https:\/\/www.plantagbiosciences.org\/people\/melanie-dibon\/category\/circular-economy\/","name":"Circular Economy","slug":"circular-economy","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.plantagbiosciences.org\/people\/melanie-dibon\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.plantagbiosciences.org\/people\/melanie-dibon\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.plantagbiosciences.org\/people\/melanie-dibon\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.plantagbiosciences.org\/people\/melanie-dibon\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}